{"id":478,"date":"2025-11-04T00:53:16","date_gmt":"2025-11-03T23:53:16","guid":{"rendered":"https:\/\/neantvert.eu\/celeste\/?p=478"},"modified":"2025-11-04T01:00:37","modified_gmt":"2025-11-04T00:00:37","slug":"a-mi-chemin","status":"publish","type":"post","link":"https:\/\/neantvert.eu\/celeste\/2025\/11\/04\/a-mi-chemin\/","title":{"rendered":"Point n\u00b02 &#8211; \u00e0 la moiti\u00e9 du projet \u266a"},"content":{"rendered":"\n<p>Bienvenue dans ce billet d\u00e9di\u00e9 \u00e0 faire le point sur l&#8217;avanc\u00e9e du projet AMV C\u00e9leste 2, installez-vous confortablement car on y f\u00eate non pas une, mais deux choses !<\/p>\n\n\n\n<p>La premi\u00e8re, c&#8217;est que <strong>il y&#8217;a cinq ans \u00e9tait officiellement annonc\u00e9 <a href=\"https:\/\/neantvert.eu\/celeste\/2020\/11\/03\/lancement-du-projet\/\">le premier AMV C\u00e9leste<\/a><\/strong> ! On visait un projet de moyen-m\u00e9trage&#8230; C&#8217;\u00e9tait une autre \u00e9poque&#8230; Bon anniversaire, en tout cas !<\/p>\n\n\n\n<p>La seconde c&#8217;est que cinq mois s&#8217;est \u00e9coul\u00e9 depuis le lancement officiel de l&#8217;AMV C\u00e9leste 2 et qu&#8217;il reste cinq mois avant la deadline du 5 avril, <strong>ce qui signifie que nous en sommes \u00e0 mi-chemin ! <\/strong>L&#8217;occasion, par cons\u00e9quence, de faire un petit bilan rapide de ces cinq premiers mois, et de commencer \u00e0 vous donner des indications pour la suite.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"498\" height=\"281\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/nico-wakatsuki.gif\" alt=\"\" class=\"wp-image-489\"\/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Donc d\u00e9j\u00e0, pour rappel, les <strong>quatre dates \u00e0 retenir pour l&#8217;instant:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>7 d\u00e9cembre: <\/strong>diffusion sur Twitch en avant-premi\u00e8re de <strong>l&#8217;Ap\u00e9ro C\u00e9leste 2<\/strong>, qui est susceptible de contenir tous les skits re\u00e7us et valid\u00e9s avant le 16 novembre<\/li>\n\n\n\n<li><strong>Fin f\u00e9vrier, date encore \u00e0 d\u00e9terminer: <\/strong>diffusion cette fois-ci de <strong>l&#8217;Ap\u00e9ro C\u00e9leste 3<\/strong><\/li>\n\n\n\n<li><strong>Dimanche 5 avril, 23h59: <\/strong>Cl\u00f4ture de la r\u00e9ception des clips, AMV et autres skits.<\/li>\n\n\n\n<li><strong>Mai, date encore \u00e0 d\u00e9terminer: <\/strong>Projection en public de <strong>l&#8217;AMV C\u00e9leste 2<\/strong> dans un cadre l\u00e0 aussi \u00e0 d\u00e9terminer, suivi apr\u00e8s de sa premi\u00e8re sur Twitch et de sa publication tout autour du monde.<\/li>\n<\/ul>\n\n\n\n<p>Encore quelques petits trucs \u00e0 d\u00e9terminer, vous l&#8217;aurez compris, mais tout commence \u00e0 s&#8217;\u00e9claircir peu \u00e0 peu, et \u00e7a \u00e7a fait plaisir.<\/p>\n\n\n\n<p>En terme de bilan pur sur ces cinq premiers mois, je vous donne l&#8217;information principale: \u00e0 l&#8217;heure actuelle j&#8217;ai donc valid\u00e9 <strong>355 clips. <\/strong>Et si vous aimez le suivi, voici un beau graphique qui donne la progression semaine par semaine: <\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c2dfad2cf&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c2dfad2cf\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"564\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-1024x564.png\" alt=\"\" class=\"wp-image-479\" srcset=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-1024x564.png 1024w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-300x165.png 300w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-150x83.png 150w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-768x423.png 768w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image.png 1380w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>En gros, un premier mois faramineux, avec 120 skits en trente jours, ce qui s&#8217;explique par l&#8217;enthousiasme que l&#8217;annonce du projet a eu sur quelques monteurs et monteuses qui, pour certains, avaient m\u00eame pr\u00e9par\u00e9s du stock en attendant le genre fatidique. J&#8217;ai aussi re\u00e7u quelques refus\u00e9s de l&#8217;AMV Enfer 4 par la m\u00eame occasion. Donc on est parti d&#8217;embl\u00e9e sur les chapeaux de roues et je vous avoue que je ne savais plus trop o\u00f9 donner la t\u00eate. <\/p>\n\n\n\n<p>L&#8217;enthousiasme est rest\u00e9 le m\u00eame durant l&#8217;\u00e9t\u00e9, l\u00e0 o\u00f9 je m&#8217;\u00e9tais attendu \u00e0 ce que \u00e7a chute pass\u00e9 le premier mois de lancement &#8211; que nenni ! 150 skits en juillet et ao\u00fbt, ce qui \u00e9tait assez impressionnant et m&#8217;avait donc encourag\u00e9 \u00e0 lancer le projet parall\u00e8le que sont les <strong>Ap\u00e9ro C\u00e9leste<\/strong>, avec le premier sorti mi septembre.<\/p>\n\n\n\n<p>On note d&#8217;ailleurs une p\u00e9riode d&#8217;accalmie en septembre, ce qui correspond \u00e0 la zone &#8220;autour&#8221; du premier Ap\u00e9ro: les deux ou trois semaines qui ont pr\u00e9c\u00e9d\u00e9es la sortie de la vid\u00e9o ont vu les monteurs et monteuses se mettre en position d&#8217;attente et prendre un peu de repos par la m\u00eame occasion. J&#8217;ai aussi ralenti mon rythme de r\u00e9ponse aux diff\u00e9rents mails, ce qui n&#8217;a pas aid\u00e9 !<\/p>\n\n\n\n<p>En tout cas le mois d&#8217;octobre fut \u00e0 nouveau fructueux, avec plus d&#8217;une cinquantaine de skits et de clips re\u00e7us et valid\u00e9s, donc on est reparti sur un \u00e9lan assez anim\u00e9 jusqu&#8217;\u00e0 l&#8217;Ap\u00e9ro C\u00e9leste 2, o\u00f9 je m&#8217;attendais \u00e0 une p\u00e9riode d&#8217;accalmie similaire pendant quelques semaines &#8211; ce qui n&#8217;est pas une mauvaise chose, loin de l\u00e0 !<\/p>\n\n\n\n<p>Si vous aimez les comparatifs, voil\u00e0 la diff\u00e9rence de rythme avec le premier AMV C\u00e9leste, sur ces cinq mois de production: <\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c2dfad5a2&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c2dfad5a2\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"564\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-2-1024x564.png\" alt=\"\" class=\"wp-image-481\" srcset=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-2-1024x564.png 1024w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-2-300x165.png 300w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-2-150x83.png 150w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-2-768x423.png 768w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/image-2.png 1381w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Les 5 premiers mois de production de l&#8217;AMV C\u00e9leste 2 compar\u00e9&#8230; aux cinq mois totaux de production de l&#8217;AMV C\u00e9leste 1<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Bon tout cela est bien beau mais on va arr\u00eater quelques minutes de se pignoler sur nos perfs et nos courbes pour \u00e0 la place plut\u00f4t s&#8217;attarder sur le contenu, et je vais l\u00e0 aussi rentrer plut\u00f4t dans le d\u00e9tail&#8230;<\/p>\n\n\n\n<p>D\u00e9j\u00e0 sur les <strong>355 skits valid\u00e9s<\/strong>, <strong>330 sont &#8220;uniques.&#8221; <\/strong>Ce que je veux dire par l\u00e0 c&#8217;est que parmi les 355 y&#8217;en a 25 qui font en r\u00e9alit\u00e9 partie d&#8217;un running gag ou d&#8217;un skit en deux parties. Par exemple, le skit Tais-toi en cinq parties qui est dans l&#8217;Ap\u00e9ro ? C&#8217;est cinq skits au sein des 355 mais un seul au sein des 330, si vous voyez ce que je veux dire.<\/p>\n\n\n\n<p>Globalement, si vous vous posez la question j&#8217;ai d\u00e9j\u00e0 re\u00e7u <strong>7 runnings gags <\/strong>\u00e0 l&#8217;heure actuelle, et par running gag je d\u00e9finis &#8220;gag \u00e9tal\u00e9 sur au moins 3 skits.&#8221; Certains durent justement 3 skits tandis le plus long en compte <em>minimum<\/em> 5. Sur ce point, je vais commencer \u00e0 tirer un peu la sonnette d&#8217;alarme car je ne pense pas avoir la place pour beaucoup plus &#8211; si vous souhaitez m&#8217;en proposer, il va falloir commencer \u00e0 \u00eatre <em>redoutable<\/em>. Pensez principalement \u00e0 un bon skit de chute, un bon skit final &#8211; c&#8217;est sans doute lui qui fera toute la diff\u00e9rence ! <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"498\" height=\"280\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/kanokari-anime-fall.gif\" alt=\"\" class=\"wp-image-488\"\/><figcaption class=\"wp-element-caption\">Ci-joint exemple de tr\u00e8s bonne chute (litt\u00e9ralement)<\/figcaption><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>En terme de contributeurs, nous sommes actuellement <strong>26 <\/strong>personnes \u00e0 avoir au moins un skit valid\u00e9. On peut monter \u00e0 <strong>29 <\/strong>si je compte toutes les personnes qui m&#8217;ont envoy\u00e9s un mail. Pour information, le premier C\u00e9leste avait &#8211; justement &#8211; 26 contributeurs \u00e9galement. Si vous vous demandez &#8220;ah bah c&#8217;est les m\u00eames alors&#8221;, bon bah parmi nos 26 contributeurs du C\u00e9leste 2, <strong>9 sont nouveaux ou nouvelles. <\/strong>Un renouvellement de 33% pour le moment ! Et on esp\u00e8re continuer \u00e0 voir de nouveaux visages \ud83d\udc4d !<\/p>\n\n\n\n<p>(Mais y&#8217;a aussi quelques anciens du premier qui nous manquent&#8230; Ils se reconna\u00eetront \ud83d\ude2a&#8230;)<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En terme de <strong>contenu<\/strong>, maintenant !<\/p>\n\n\n\n<p>Sur les 330 skits, <strong>250 sont musicaux <\/strong>et <strong>80 sont parl\u00e9s. <\/strong>En gros on est sur trois quarts de musicaux et un quart de parl\u00e9. <strong>C&#8217;est exactement l&#8217;\u00e9quilibre que je recherche personnellement en tant que r\u00e9alisateur.<\/strong> On pourrait avoir un chouia peu plus de parl\u00e9 que \u00e7a serait pas mal mais globalement <em>\u00e7a me va.<\/em><\/p>\n\n\n\n<p>En terme de dur\u00e9e, c&#8217;est&#8230; plut\u00f4t \u00e9quilibr\u00e9.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c2dfad8dc&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c2dfad8dc\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"641\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-1024x641.png\" alt=\"\" class=\"wp-image-484\" srcset=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-1024x641.png 1024w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-300x188.png 300w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-150x94.png 150w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-768x481.png 768w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image.png 1326w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Pour l&#8217;instant je reste en position d&#8217;attente et je regarde comment les choses \u00e9voluent donc je n&#8217;ai pas d&#8217;alerte \u00e0 donner. En tant que r\u00e9alisateur, <strong>je ne serais n\u00e9anmoins pas contre un peu plus de skits courts<\/strong> (si possible entre 6 et 10s) sachant qu&#8217;en parall\u00e8le je vais <strong>rester vigilant sur les skits tr\u00e8s longs. <\/strong>En vrai beaucoup dans ce 6% sont des skits de 31 ou 32s qui d\u00e9passent l\u00e9g\u00e8rement la limite &#8211; le plus long est \u00e0 37s, ce qui reste acceptable. Le vrai souci \u00e9tant que les skits longs, mine de rien, prennent vite beaucoup de place dans un projet: avec juste ces 6% de vid\u00e9os j&#8217;ai d\u00e9j\u00e0 <em>un quart d&#8217;heure de contenu<\/em> donc <em>\u00e7a va vite.<\/em><\/p>\n\n\n\n<p>Apr\u00e8s, l\u00e0 aussi, mon objectif est pas de vous d\u00e9courager &#8211; au contraire, je vous encourage \u00e0 me sortir des bons bangers dans ce cadre l\u00e0, mais sachez qu&#8217;il va falloir donner le meilleur de vous m\u00eame h\u00e9h\u00e9. Mais si \u00e7a marche, alors l\u00e0 bienvenue dans l&#8217;immortalit\u00e9, aux c\u00f4t\u00e9s du skit Berserk sur Gims &amp; Vitaa du premier C\u00e9leste.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En terme de langue maintenant, c&#8217;est l\u00e0 que c&#8217;est rigolo &#8211; <\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c2dfadb2a&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c2dfadb2a\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"659\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-1-1024x659.png\" alt=\"\" class=\"wp-image-485\" srcset=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-1-1024x659.png 1024w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-1-300x193.png 300w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-1-150x96.png 150w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-1-768x494.png 768w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-1.png 1188w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">A noter qu&#8217;on prend ici en compte la langue &#8220;majoritaire&#8221; de chaque clip &#8211; si une chanson est majoritairement en italien avec quelques paroles en anglais, on comptera &#8220;italien&#8221;, par exemple.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Majorit\u00e9 \u00e9crasante pour le fran\u00e7ais, ce qui n&#8217;est absolument pas illogique. L&#8217;anglais se d\u00e9fend tr\u00e8s bien, comme \u00e0 son habitude, et les instrumentaux (souvent des OST de jeu vid\u00e9o) sont bien repr\u00e9sent\u00e9s. Et apr\u00e8s, c&#8217;est une pr\u00e9sence grandissante des&#8230; skits en allemand !? Ok pourquoi pas. Les chansons italiennes sont l\u00e0 aussi de passage, c&#8217;est bien not\u00e9.<\/p>\n\n\n\n<p>Dans le champ &#8220;autres&#8221; on retrouve toutes les langues avec un seul clip, ce qui englobe le croate, le su\u00e8dois, le finnois, le telugu, le &#8220;latin&#8221; et, \u00e9videmment, la langue des chevaux (litt\u00e9ralement.) On devient INTERNATIONAL \ud83c\udf0d. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"498\" height=\"498\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/sips-tea-frieren.gif\" alt=\"\" class=\"wp-image-487\"\/><figcaption class=\"wp-element-caption\">Quand on relit ses manuels de grammaire telugu pour traduire le skit<\/figcaption><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Enfin en terme d&#8217;animes, un comptage un peu brut en compte <strong>258 diff\u00e9rents <\/strong>repr\u00e9sent\u00e9s au sein des 330 skits uniques. Sachant que je compte chaque anime qui appara\u00eet, y compris dans des skits avec plusieurs sources diff\u00e9rentes, ce qui peut vite faire exploser le compteur. Si on retire ces skits, je pense qu&#8217;on est plus autour de 230&#8230; ce qui est d\u00e9j\u00e0 pas mal ! <\/p>\n\n\n\n<p>Les anim\u00e9s les plus populaires pour le moment sont <strong>Dandadan <\/strong>et <strong>Bocchi the Rock<\/strong>, tous deux avec 6 skits. Si on prend une saga dans son &#8220;int\u00e9gralit\u00e9&#8221;, vous serez heureux d&#8217;apprendre que, tous anim\u00e9s confondus, j&#8217;ai 7 skits <strong>Uma Musume<\/strong> ! <\/p>\n\n\n\n<p>Apr\u00e8s \u00e7a on retrouve un petit groupes d&#8217;animes avec 4 skits &#8211; <em>Jojo&#8217;s Bizarre Adventure<\/em>, <em>Demon Slayer, Golden Kamuy<\/em>, <em>My Hero Academia, Oshi no Ko, Evangelion <\/em>et&#8230; <em>Princess Tutu ? <\/em>Quelqu&#8217;un a \u00e9t\u00e9 tr\u00e8s motiv\u00e9 \ud83e\udd86.<\/p>\n\n\n\n<p>Pour l&#8217;instant, pas de s\u00e9ries &#8220;bannies&#8221; pour cause de trop de skits &#8211; ce n&#8217;est plus une r\u00e8gle d&#8217;actualit\u00e9 pour le moment, on verra durant le dernier mois de production&#8230; <\/p>\n\n\n\n<p>En terme d&#8217;\u00e9poque couverte, hop l\u00e0 boum &#8211; <\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c2dfade33&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c2dfade33\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"641\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-2-1024x641.png\" alt=\"\" class=\"wp-image-486\" srcset=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-2-1024x641.png 1024w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-2-300x188.png 300w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-2-150x94.png 150w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-2-768x481.png 768w, https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/image-2.png 1326w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Oui \u00e7a commence \u00e0 <strong>1917 <\/strong>parce que pensez bien que quelqu&#8217;un a vu le skit Serpent Blanc du premier C\u00e9leste et s&#8217;est dit que y&#8217;avait un d\u00e9fi \u00e0 se donner ! <\/p>\n\n\n\n<p>Sans surprise, les anim\u00e9s les plus r\u00e9cents sont les plus populaires: c&#8217;est ceux qui sont les plus frais dans l&#8217;esprit des monteurs &amp; monteuses, les sources de bonne qualit\u00e9 sont facile \u00e0 trouver, donc rien d&#8217;illogique l\u00e0 dedans. Je dirais pas non \u00e0 plus d&#8217;anime des ann\u00e9es 80 et 90 mais l\u00e0 c&#8217;est un d\u00e9sir personnel plus qu&#8217;une vraie exigence ! <\/p>\n\n\n\n<p>En r\u00e8gle g\u00e9n\u00e9rale, en tant que r\u00e9alisateur, <strong>j&#8217;encourage \u00e0 monter sur des s\u00e9ries populaires. <\/strong>On en a quelques unes bien repr\u00e9sent\u00e9es (<em>My Hero Academia<\/em>, <em>Dandadan<\/em>, <em>Demon Slayer<\/em>) mais je serais pas contre un peu plus de pr\u00e9sence de ces &#8220;piliers communs&#8221; de l&#8217;animation qui pourront parler \u00e0 un public tr\u00e8s large. Je pense \u00e0 <em>Spy x Family, Solo Leveling, Jujutsu Kaisen<\/em>, <em>Naruto<\/em> ou bien <em>Haikyuu<\/em> par exemple&#8230;<\/p>\n\n\n\n<p>(Mais n&#8217;ayez pas peur de sortir des trucs tr\u00e8s obscurs \u00e9galement ! On est l\u00e0 pour s&#8217;amuser et emphaser la grande vari\u00e9t\u00e9 de l&#8217;animation japonaise !)<\/p>\n\n\n\n<p>(Je veux juste pas que vous oubliez les grands classiques populaires, qui ont pour certains des grands potentiels inexplor\u00e9s qui feront <em>remuer les foules<\/em> \u261d\ufe0f\ud83e\udd13 !)<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"498\" height=\"281\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/nanami-jujutsu-kaisen.gif\" alt=\"\" class=\"wp-image-491\"\/><figcaption class=\"wp-element-caption\">TLDR &#8211; J&#8217;ai toujours pas re\u00e7u de skit sur Nanami et \u00e7a me rend tr\u00e8s triste, il m\u00e9rite d&#8217;\u00eatre l\u00e0 dans le C\u00e9leste 2<\/figcaption><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Toutes ces stats \u00e9tant pos\u00e9es de mani\u00e8re rigolote, pour faire un <strong>bilan rapide de ces 5 premiers mois&#8230; <\/strong><\/p>\n\n\n\n<p>Bon d\u00e9j\u00e0 l\u00e0 je vous ai fait un pav\u00e9 statistique et tout, c&#8217;est avant tout pour les quelques gourmands de la courbe qui sont sur le Discord et qui se reconna\u00eetront, mais en g\u00e9n\u00e9ral <strong>ne vous prenez pas la t\u00eate et envoyez moi des trucs qui vous font plaisir. <\/strong>Oh puis tant qu&#8217;\u00e0 faire, envoyez moi aussi ce qui vous fait pas plaisir et les skits que vous avez mont\u00e9 et que vous d\u00e9testez &#8211; c&#8217;est pas anormal de d\u00e9tester un truc qu&#8217;on a mont\u00e9 et qui correspond pas totalement \u00e0 ce qu&#8217;on a envisag\u00e9, mais un oeil neuf pourra vous rassurer ou vous donner des indications plus pr\u00e9cises. C&#8217;est mon r\u00f4le, tout comme cela peut \u00eatre le r\u00f4le du Discord. Vous n&#8217;\u00eates pas seuls ! <\/p>\n\n\n\n<p>Et si vous stressez parce que ce vous avez pu voir dans l&#8217;AMV C\u00e9leste 1 vous a donn\u00e9 le sentiment que monter des skits demande des comp\u00e9tences que vous n&#8217;avez pas, j&#8217;ai une bonne nouvelle: en tant que r\u00e9alisateur, l\u00e0 j&#8217;en suis \u00e0 un point <strong>o\u00f9 j&#8217;ai &#8220;besoin&#8221; de petits skits simples et l\u00e9gers. <\/strong>J&#8217;ai re\u00e7u beaucoup de gros montages, de gros skits musicaux tr\u00e8s mont\u00e9s et tr\u00e8s l\u00e9ch\u00e9s, ils sont supers et j&#8217;ai h\u00e2te de continuer \u00e0 en recevoir parce que clairement y&#8217;a des gens dans le crew qui montent en niveau et qui se font de plus en plus plaisir, mais \u00e7a ne veut pas dire que des skits au montage simple, en deux plans et demi et qui font des gags tr\u00e8s simples, je n&#8217;en veux pas. Au contraire ! D&#8217;un point de vue rythme, ambiance et humour, \u00e7a peut me faire beaucoup de bien \ud83d\ude0a !<\/p>\n\n\n\n<p>En r\u00e8gle g\u00e9n\u00e9ral, <strong>je rejette peu de skits. <\/strong>Ca veut pas dire que tout ce que je re\u00e7ois est d&#8217;embl\u00e9e valid\u00e9 ou que j&#8217;accepte tout par d\u00e9sespoir: c&#8217;est juste que je fais retravailler autant que possible tout ce que je re\u00e7ois pour pouvoir l&#8217;accepter sans pression ni piti\u00e9. Les skits rejet\u00e9s c&#8217;est rarement pour des raisons techniques, c&#8217;est souvent plus pour des id\u00e9es qui marchent pas si bien, qui ont trop d\u00e9j\u00e0 \u00e9t\u00e9 faites ailleurs, qui sont pas forc\u00e9ment tr\u00e8s compr\u00e9hensibles ou qui clairement ne peuvent pas \u00eatre exprim\u00e9es en moins de 30s. &#8221; La technique \u00e7a se travaille mais en r\u00e9alit\u00e9 atteindre un niveau &#8220;acceptable&#8221; en montage n&#8217;est pas si compliqu\u00e9 qu&#8217;on pourrait le croire&#8230; et surtout vous n&#8217;avez pas \u00e0 avoir peur de devoir avoir un niveau solide d&#8217;embl\u00e9e ! <\/p>\n\n\n\n<p>Tout \u00e7a pour dire que <strong>j&#8217;encourage plus que jamais l&#8217;apparition de nouveaux visages. <\/strong>C&#8217;est mon vrai espoir pour ces cinq prochains mois &#8211; que je continue \u00e0 avoir des nouvelles personnes qui viennent nous rejoindre, chacunes avec leurs id\u00e9es, leurs passions, leur fa\u00e7on de monter. Bref c&#8217;est un peu id\u00e9aliste mais plus on aura de profils diff\u00e9rents, plus il y&#8217;aura du fun &#8211; je pense ? <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"498\" height=\"281\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/nana.gif\" alt=\"\" class=\"wp-image-490\"\/><figcaption class=\"wp-element-caption\">C&#8217;est ce que Nana de Nana dirait, je crois<\/figcaption><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>Autre sujet: <strong>commencez \u00e0 consid\u00e9rer la trilogie des<\/strong> <strong>Ap\u00e9ro C\u00e9leste comme faisant partie int\u00e9grante de l&#8217;AMV C\u00e9leste 2<\/strong>. Je vais pas vous faire un dessin mais si je re\u00e7ois autant de skits ces 5 prochains mois que j&#8217;en ai re\u00e7u les 5 pr\u00e9c\u00e9dents (et \u00e7a commence \u00e0 ne plus me para\u00eetre <em>improbable<\/em>), je finirais au total avec 700 skits soit l&#8217;\u00e9quivalent de 2 AMV C\u00e9leste complets&#8230; avec en plus 100 skits en rab. <\/p>\n\n\n\n<p>Encore une fois je m&#8217;adapterais, on r\u00e9fl\u00e9chira \u00e0 ce qu&#8217;on peut faire de tout \u00e7a, j&#8217;ai plusieurs id\u00e9es ou pistes&#8230; mais vraiment dites vous d\u00e8s \u00e0 pr\u00e9sent qu&#8217;en matant un Ap\u00e9ro C\u00e9leste, en fait, vous matez pas un bonus ou un spin-off &#8211; vous matez d\u00e9j\u00e0 l&#8217;AMV C\u00e9leste 2 ! Ce qui veut dire que j&#8217;essaierais de continuer \u00e0 soigner ces courts-m\u00e9trage &#8211; j&#8217;ai d\u00e9j\u00e0 tr\u00e8s h\u00e2te de monter le second Ap\u00e9ro vu la quantit\u00e9 de skits de qualit\u00e9 que j&#8217;ai \u00e0 ma disposition, et j&#8217;esp\u00e8re qu&#8217;il vous plaira ! L&#8217;intro est d\u00e9j\u00e0 l\u00e0, tr\u00e8s rigolote, on commence tranquilou \u00e0 bosser sur l&#8217;ending, j&#8217;ai quelques id\u00e9es de skits que je veux caser&#8230; Bref, cool \ud83d\ude0e !<\/p>\n\n\n\n<p> <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"374\" height=\"374\" src=\"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/11\/sunglasses-glasses.gif\" alt=\"\" class=\"wp-image-492\"\/><figcaption class=\"wp-element-caption\">\ud83d\ude0e<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Enfin pour conclure &#8211; je ne sais pas encore si je remettrais en place le <strong>concept de bingo <\/strong>du premier C\u00e9leste, l\u00e0 \u00e7a va \u00eatre moins n\u00e9cessaire vu la quantit\u00e9 de skits re\u00e7us. Mais j&#8217;ai quand m\u00eame envie de faire une ptite initiative un peu joueuse, \u00e7a sera sans doute des succ\u00e8s ou des mini-d\u00e9fis, on verra&#8230; En tout cas, en terme de challenge, l\u00e0 les monteurs et monteuses du Discord se lancent dans un petit projet de <strong>Secret Santa des AMV<\/strong>, \u00e7a va sans doute donner quelques trucs un peu maudits&#8230; Exactement comme l&#8217;aurait voulu Saint Nicolas, ho ho ho&#8230;<\/p>\n\n\n\n<p>Bref, ravi de comment \u00e7a se passe, et j&#8217;ai h\u00e2te de voir comment ces prochains mois vont continuer \u00e0 se d\u00e9rouler. Ce point c&#8217;est beaucoup de stats, beaucoup de blabla et d&#8217;analyse, mais au fond c&#8217;est que du plaisir, et \u00e7a me fait beaucoup de bien personnellement. Merci \u00e0 toutes et tous pour votre confiance en ce projet, et en vous donnant tr\u00e8s vite rendez-vous &#8211; dans un mois donc &#8211; pour un second Ap\u00e9ro qui devrait mettre &#8220;f\u00eate&#8221; dans le mot&#8230; euh&#8230; &#8220;f\u00eate de fin d&#8217;ann\u00e9e&#8230;&#8221;<\/p>\n\n\n\n<p>Ah merde ma chute est nulle &#8211; faites pas \u00e7a si vous avez des projets de running gag&#8230;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On est \u00e0 mi-chemin du parcours qui nous s\u00e9pare de l&#8217;AMV C\u00e9leste 2 ! Alors, comment est-ce que tout \u00e7a \u00e9volue ?<\/p>\n","protected":false},"author":1,"featured_media":483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[4,6],"class_list":["post-478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amv-celeste-2","tag-amv-celeste","tag-point-regulier"],"jetpack_featured_media_url":"https:\/\/neantvert.eu\/celeste\/wp-content\/uploads\/2025\/10\/DANDADAN-83-e1762208091395.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/posts\/478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/comments?post=478"}],"version-history":[{"count":8,"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/posts\/478\/revisions"}],"predecessor-version":[{"id":500,"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/posts\/478\/revisions\/500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/media\/483"}],"wp:attachment":[{"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/media?parent=478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/categories?post=478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neantvert.eu\/celeste\/wp-json\/wp\/v2\/tags?post=478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}